{"id":1636,"date":"2023-02-19T17:07:13","date_gmt":"2023-02-19T17:07:13","guid":{"rendered":"https:\/\/macaritravel.com\/blog\/?post_type=podcast&#038;p=1636"},"modified":"2023-03-06T11:21:37","modified_gmt":"2023-03-06T11:21:37","slug":"episodio-9","status":"publish","type":"podcast","link":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/","title":{"rendered":"Epis\u00f3dio #9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na nona edi\u00e7\u00e3o do podcast <strong>TIP<\/strong> temos como convidado o Andr\u00e9 Piazza.<\/p>\n\n\n\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-10 has-background-dim\"><\/span><img decoding=\"async\" width=\"640\" height=\"360\" class=\"wp-block-cover__image-background wp-image-1637 lazyload\" alt=\"\" data-src=\"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2023\/02\/Skype-20230215-192614.jpeg\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/360;object-position:50% 82%\" data-object-fit=\"cover\" data-object-position=\"50% 82%\" data-srcset=\"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2023\/02\/Skype-20230215-192614.jpeg 640w, https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2023\/02\/Skype-20230215-192614-300x169.jpeg 300w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\">Andr\u00e9, Adriana e Ricardo na sala virtual do TIP.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">O Andr\u00e9 \u00e9 gerente de produto em cyber seguranca e vive atualmente em Austin (Texas) nos Estados Unidos da America e transformou o podcast numa sensacional masterclass.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-30912a56-db56-45ac-ac5d-62ecb2bff148\">Neste epis\u00f3dio:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-cf093fd1-bacb-4e1e-8ca1-ce53b88aeaf9\"><strong>Senta que l\u00e1 vem historia<\/strong>: O Andr\u00e9 compartilhou uma hist\u00f3ria ocorrida durante uma viagem a neg\u00f3cios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-cf093fd1-bacb-4e1e-8ca1-ce53b88aeaf9\"><strong>Ponto a Ponto:<\/strong> Conversamos sobre <strong>os problemas do Airbnb.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-cf093fd1-bacb-4e1e-8ca1-ce53b88aeaf9\"><strong>Bora l\u00e1<\/strong>: Como sugest\u00e3o de destino o Andr\u00e9 contou algumas historias e deu dicas sobre Pequim (China).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira alguns links citados neste epis\u00f3dio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/octanage.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Octanage Podcast<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.shangri-la.com\/en\/beijing\/chinaworld\/\" target=\"_blank\" rel=\"noreferrer noopener\">China World Hotel<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.theinvisibletourist.com\/why-you-shouldnt-use-airbnb-issues-you-didnt-know\/\" target=\"_blank\" rel=\"noreferrer noopener\">Why you shouldn&#8217;t use Airbnb<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/pt.wikipedia.org\/wiki\/Cidade_Proibida\" target=\"_blank\" rel=\"noreferrer noopener\">Cidade Proibida<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.civitatis.com\/pt\/pequim\/?ag_aid=42169\" target=\"_blank\" rel=\"noreferrer noopener\">Mercado da Seda e outras atividades em Pequim<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tem perguntas? D\u00favidas? Quer deixar seu coment\u00e1rio? <a href=\"https:\/\/macaritravel.com\/br\/contatos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Envie um email pra gente!<\/a><\/p>\n\n\n\n<div class=\"ictab-main-container-wrap ictab-clearfix ictab-bgsection-custom\" id=\"ictab-random-725937613\" style=\"width:;height:;\">\r\n    <div class=\"ictab-available-template-wrap ictab-template3\">\r\n          <div class=\"ictab-inner-wrapper ictab-bgcolor-wrap ictab-parallax-enabled ictab-parallax-for-videos-fixes\"  style=\"background-color:#dd9933\">   \r\n                            <div class=\"ictab-common-overlay\"><\/div>\r\n                                    <div class=\"ictab-single-content-wrapper\">\r\n<div class=\"ictab-content-wrap-section\">\r\n <div class=\"ictab-header-text-wrap wow animated fadeInRight\">\r\n <h3>Macari Travel <\/h3>\r\n<\/div>\r\n\r\n <div class=\"ictab-description-content-wrap wow animated fadeInUp\">\r\n  Viagens incr\u00edveis? Somos especialistas!<\/div>\r\n <div class=\"ictab-ctabbutton-wrap\">\r\n <div class=\"ictab-btn-wrap ictab-button-wrap  wow animated fadeInLeft\" id=\"ictab-btn1-821204744\">\r\n   <div class=\"ictab-button-main-wrap \">\r\n    <a href=\"https:\/\/app.leadster.com.br\/capture\/nhN7xpHVG0c89b64\"   \r\n      class=\"ictab-btn-tag ictab_show_both ictab-external-btn-type \r\n      button-shine\" target='_blank' data-text=\"Entre em Contato\">\r\n        <span data-text='Entre em Contato'>Entre em Contato<\/span>    <\/a>\r\n   <\/div>\r\n<\/div>\r\n<style>\r\n<\/style>\r\n<\/div>   <\/div>\r\n<\/div>\r\n         <\/div>\r\n    <\/div>\r\n<style type='text\/css' media='all'>\r\n.ictab-main-container-wrap#ictab-random-725937613 .ictab-header-text-wrap h3 {  }\r\n\r\n\r\n    <\/style>\r\n<style type='text\/css' media='all'>\r\n#ictab-random-725937613 .ictab-template3 .ictab-content-wrap-section:before{\r\nbackground-color:#ddb033;\r\n}\r\n#ictab-random-725937613 .ictab-template4 .ictab-inner-wrapper .ictab-content-wrap-section{\r\nbackground:#ddb033;\r\n}\r\n\r\n#ictab-random-725937613 .ictab-template36 .ictab-double-content-wrapper .ictab-content-wrap-section .ictab-left-content-wrap{\r\n   background:#ddb033; \r\n}\r\n<\/style>\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.<\/p>\n","protected":false},"author":1,"featured_media":810,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","episode_type":"audio","audio_file":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2023\/02\/TIP-9-18022023.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"1:12:28","filesize":"66.42M","filesize_raw":"69647858","date_recorded":"2023-02-19 17:07:13","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"tags":[223,220,53,218,98,222,21,219,217,224,221,216,156,14],"series":[371],"speaker":[84,215,83],"class_list":["post-1636","podcast","type-podcast","status-publish","has-post-thumbnail","hentry","tag-airbnb","tag-andre-piazza","tag-aviao","tag-brexit","tag-china","tag-cidade-proibida","tag-dicas","tag-gibraltar","tag-irlanda","tag-mercado-da-seda","tag-octanage-podcast","tag-pequim","tag-reino-unido","tag-roteiro","series-tip-turismo-inteligente-podcast","speaker-adrianatamy","speaker-andre-piazza","speaker-macari"],"episode_featured_image":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1.jpg","episode_player_image":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1-1.jpg","download_link":"https:\/\/macaritravel.com\/blog\/podcast-download\/1636\/episodio-9.mp3","player_link":"https:\/\/macaritravel.com\/blog\/podcast-player\/1636\/episodio-9.mp3","audio_player":null,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/us\/podcast\/tip-turismo-inteligente-podcast\/id1648052487","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"rss":{"key":"rss","url":"https:\/\/macaritravel.com\/blog\/feed\/podcast\/","label":"RSS","class":"rss","icon":"rss.png"},"spotify":{"key":"spotify","url":"https:\/\/open.spotify.com\/show\/6EgKH7yuymuo9I9kZjhMEG","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/macaritravel.com\/blog\/feed\/podcast\/tip-turismo-inteligente-podcast","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"MgCmu6Jl9g\"><a href=\"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/\">Epis\u00f3dio #9<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/embed\/#?secret=MgCmu6Jl9g\" width=\"500\" height=\"350\" title=\"&#8220;Epis\u00f3dio #9&#8221; &#8212; Macari Travel Blog\" data-secret=\"MgCmu6Jl9g\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/macaritravel.com\/blog\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Epis\u00f3dio #9 - Macari Travel Blog<\/title>\n<meta name=\"description\" content=\"Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Epis\u00f3dio #9 - Macari Travel Blog\" \/>\n<meta property=\"og:description\" content=\"Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/\" \/>\n<meta property=\"og:site_name\" content=\"Macari Travel Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MacariTravel\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T11:21:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/\",\"name\":\"Epis\u00f3dio #9 - Macari Travel Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-TIP-redondo1.jpg\",\"datePublished\":\"2023-02-19T17:07:13+00:00\",\"dateModified\":\"2023-03-06T11:21:37+00:00\",\"description\":\"Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-TIP-redondo1.jpg\",\"contentUrl\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-TIP-redondo1.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/episodio-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast\",\"item\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/podcast\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Epis\u00f3dio #9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/\",\"name\":\"Blog da Macari Travel\",\"description\":\"Blog Oficial da Macari Travel\",\"publisher\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#organization\",\"name\":\"Macari Travel\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-MT-Oficial.png\",\"contentUrl\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-MT-Oficial.png\",\"width\":1350,\"height\":600,\"caption\":\"Macari Travel\"},\"image\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacariTravel\",\"https:\\\/\\\/www.instagram.com\\\/macari_travel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Epis\u00f3dio #9 - Macari Travel Blog","description":"Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/","og_locale":"pt_BR","og_type":"article","og_title":"Epis\u00f3dio #9 - Macari Travel Blog","og_description":"Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.","og_url":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/","og_site_name":"Macari Travel Blog","article_publisher":"https:\/\/www.facebook.com\/MacariTravel","article_modified_time":"2023-03-06T11:21:37+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/","url":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/","name":"Epis\u00f3dio #9 - Macari Travel Blog","isPartOf":{"@id":"https:\/\/macaritravel.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/#primaryimage"},"image":{"@id":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/#primaryimage"},"thumbnailUrl":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1.jpg","datePublished":"2023-02-19T17:07:13+00:00","dateModified":"2023-03-06T11:21:37+00:00","description":"Na nona edi\u00e7\u00e3o do podcast TIP temos como convidado o Andr\u00e9 Piazza.","breadcrumb":{"@id":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/#primaryimage","url":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1.jpg","contentUrl":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-TIP-redondo1.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/macaritravel.com\/blog\/podcast\/episodio-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/macaritravel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Podcast","item":"https:\/\/macaritravel.com\/blog\/podcast\/"},{"@type":"ListItem","position":3,"name":"Epis\u00f3dio #9"}]},{"@type":"WebSite","@id":"https:\/\/macaritravel.com\/blog\/#website","url":"https:\/\/macaritravel.com\/blog\/","name":"Blog da Macari Travel","description":"Blog Oficial da Macari Travel","publisher":{"@id":"https:\/\/macaritravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/macaritravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/macaritravel.com\/blog\/#organization","name":"Macari Travel","url":"https:\/\/macaritravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/macaritravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-MT-Oficial.png","contentUrl":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-MT-Oficial.png","width":1350,"height":600,"caption":"Macari Travel"},"image":{"@id":"https:\/\/macaritravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacariTravel","https:\/\/www.instagram.com\/macari_travel\/"]}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/podcast\/1636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/comments?post=1636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/media\/810"}],"wp:attachment":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/media?parent=1636"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/tags?post=1636"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/series?post=1636"},{"taxonomy":"speaker","embeddable":true,"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/speaker?post=1636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}