{"id":106,"count":1,"description":"","link":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/","name":"Cairo","slug":"cairo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Cairo - Macari Travel Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/macaritravel.com\/blog\/tag\/cairo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Cairo - Macari Travel Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/macaritravel.com\/blog\/tag\/cairo\/\" \/>\n<meta property=\"og:site_name\" content=\"Macari Travel Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/tag\\\/cairo\\\/\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/tag\\\/cairo\\\/\",\"name\":\"Arquivos Cairo - Macari Travel Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/tag\\\/cairo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/tag\\\/cairo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cairo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/\",\"name\":\"Blog da Macari Travel\",\"description\":\"Blog Oficial da Macari Travel\",\"publisher\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#organization\",\"name\":\"Macari Travel\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-MT-Oficial.png\",\"contentUrl\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-MT-Oficial.png\",\"width\":1350,\"height\":600,\"caption\":\"Macari Travel\"},\"image\":{\"@id\":\"https:\\\/\\\/macaritravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacariTravel\",\"https:\\\/\\\/www.instagram.com\\\/macari_travel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Cairo - Macari Travel Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Cairo - Macari Travel Blog","og_url":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/","og_site_name":"Macari Travel Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/","url":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/","name":"Arquivos Cairo - Macari Travel Blog","isPartOf":{"@id":"https:\/\/macaritravel.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/macaritravel.com\/blog\/tag\/cairo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/macaritravel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cairo"}]},{"@type":"WebSite","@id":"https:\/\/macaritravel.com\/blog\/#website","url":"https:\/\/macaritravel.com\/blog\/","name":"Blog da Macari Travel","description":"Blog Oficial da Macari Travel","publisher":{"@id":"https:\/\/macaritravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/macaritravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/macaritravel.com\/blog\/#organization","name":"Macari Travel","url":"https:\/\/macaritravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/macaritravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-MT-Oficial.png","contentUrl":"https:\/\/macaritravel.com\/blog\/wp-content\/uploads\/2022\/10\/Logo-MT-Oficial.png","width":1350,"height":600,"caption":"Macari Travel"},"image":{"@id":"https:\/\/macaritravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacariTravel","https:\/\/www.instagram.com\/macari_travel\/"]}]}},"_links":{"self":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/tags\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/posts?tags=106"},{"href":"https:\/\/macaritravel.com\/blog\/wp-json\/wp\/v2\/podcast?tags=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}